{"id":4220,"date":"2025-11-16T20:26:23","date_gmt":"2025-11-16T20:26:23","guid":{"rendered":"https:\/\/eticamedia.eu\/?p=4220"},"modified":"2026-04-23T12:12:49","modified_gmt":"2026-04-23T12:12:49","slug":"friedliches-dorf","status":"publish","type":"post","link":"https:\/\/eticamedia.eu\/en\/schoene-news\/friedliches-dorf\/","title":{"rendered":"Adventskalender Friedliches Dorf"},"content":{"rendered":"<p><a href=\"https:\/\/eticamedia.eu\/en\/product\/friedliches-dorf\/\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4052 size-medium\" src=\"https:\/\/i0.wp.com\/eticamedia.eu\/wp-content\/uploads\/2023\/11\/P1000398.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" \/>. \u00a0 \u00a0<\/a><a href=\"https:\/\/eticamedia.eu\/en\/product\/friedliches-dorf\/\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4222 size-medium\" src=\"https:\/\/i0.wp.com\/eticamedia.eu\/wp-content\/uploads\/2023\/11\/P1000532.jpg?resize=300%2C225&#038;ssl=1\" alt=\"Friedliches Dorf Papiermodell Advent\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p>Die Zeichnungen auf den Baus\u00e4tzen sind alle liebevoll von Hand gefertigt.<\/p>\n<p>Das Basteln des Papiermodells hat meditative Wirkung &#8211; f\u00fcr eine friedvolle und besinnliche Auszeit von den Bedr\u00e4ngnissen der Gegenwart.<\/p>\n<p>Die vierundzwanzig Bauwerke, bestehend aus einer Kirche, einer M\u00fchle und H\u00e4usern, ergeben zusammen einen m\u00e4rchenhaften Adventskalender, Dekoration f\u00fcr das Zuhause oder als Baumschmuck &#8211; zur Weihnachtszeit oder das ganze Jahr \u00fcber.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-4054 alignright\" src=\"https:\/\/i0.wp.com\/eticamedia.eu\/wp-content\/uploads\/2023\/11\/P1000404-rotated-e1732539435390-225x300.jpg?resize=197%2C263&#038;ssl=1\" alt=\"Adventskalender Friedliches Dorf zum Basteln aus Papier\" width=\"197\" height=\"263\" \/>Ein\u00a0wundersch\u00f6ner, farbenfroher und doch edler Hingucker, den nicht jeder hat.<\/p>\n<ul>\n<li>Papiermodell in vierundzwanzig Miniaturen aus Papier (ohne Deko).<\/li>\n<li>Als Adventskalender nutzbar (Beigef\u00fcgte Zahlen lassen sich auf die Bauwerke kleben)<\/li>\n<li>Das Modell hat aufgebaut eine Gr\u00f6\u00dfe von ca. 40 x 50 cm.<\/li>\n<li>Der Aufbau der Bastelb\u00f6gen gelingt leicht mit Schere und Klebe<\/li>\n<li>Unter die 24\u00a0Bauwerke lassen sich als Kalender bequem kleine K\u00f6stlichkeiten oder \u00dcberraschungen verstecken.<\/li>\n<li>Oder Sie nutzen die Miniaturen einzeln, als Baumschmuck oder Tischdeko das ganze Jahr \u00fcber.<\/li>\n<\/ul>\n<p>Der Papierbausatz kostet 18,90 Euro und ist <a href=\"https:\/\/eticamedia.eu\/en\/product\/friedliches-dorf\/\">hier bei uns erh\u00e4ltlich<\/a>.<\/p>\n<p><a href=\"https:\/\/eticamedia.eu\/en\/product\/friedliches-dorf\/\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4051 size-medium\" src=\"https:\/\/i0.wp.com\/eticamedia.eu\/wp-content\/uploads\/2023\/11\/Hand-Friedl-Dorf.png?resize=225%2C300&#038;ssl=1\" alt=\"\" width=\"225\" height=\"300\" \/>\u00a0<\/a><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4224 size-medium\" src=\"https:\/\/i0.wp.com\/eticamedia.eu\/wp-content\/uploads\/2023\/11\/P1000546-rotated-e1732550168269-225x300.jpg?resize=225%2C300&#038;ssl=1\" alt=\"Friedliches Dorf Papiermodell Advent\" width=\"225\" height=\"300\" \/><\/p>\n<p>&nbsp;<\/p>\n<a href='https:\/\/eticamedia.eu\/en\/product\/friedliches-dorf\/' class='small-button smallsilver'>Zum Papiermodell &#8222;Friedliches Dorf&#8220;<\/a>\n<p>Weitere Papiermodelle sind hier zu finden: https:\/\/www.adventwerkstatt.de\/<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Basteln des Papiermodells hat meditative Wirkung &#8211; f\u00fcr eine friedvolle und besinnliche Auszeit von den Bedr\u00e4ngnissen der Gegenwart. Handgezeichnet. <\/p>","protected":false},"author":2,"featured_media":4050,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[36],"tags":[108,91],"class_list":["post-4220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoene-news","tag-advent","tag-kunstvolles","pmpro-has-access"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eticamedia.eu\/wp-content\/uploads\/2023\/11\/Friedliches-Dorf.png?fit=3508%2C2480&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/posts\/4220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/comments?post=4220"}],"version-history":[{"count":16,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/posts\/4220\/revisions"}],"predecessor-version":[{"id":4228,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/posts\/4220\/revisions\/4228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/media\/4050"}],"wp:attachment":[{"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/media?parent=4220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/categories?post=4220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eticamedia.eu\/en\/wp-json\/wp\/v2\/tags?post=4220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}